{"id":38049,"date":"2024-09-24T20:38:42","date_gmt":"2024-09-24T18:38:42","guid":{"rendered":"https:\/\/www.registrocentral.es\/juzgado-de-paz\/?post_type=juzgado-de-paz&#038;p=38049"},"modified":"2024-09-24T20:38:42","modified_gmt":"2024-09-24T18:38:42","slug":"ezkio-itsaso","status":"publish","type":"juzgado-de-paz","link":"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/ezkio-itsaso\/","title":{"rendered":"Ezkio-Itsaso"},"content":{"rendered":"<p>El Juzgado de Paz de Ezkio-Itsaso ofrece una serie de servicios judiciales y civiles esenciales para los residentes de la localidad. Si necesitas realizar tr\u00e1mites relacionados con el estado civil, actas, o demandas menores, aqu\u00ed te explicamos todo lo que necesitas saber para gestionar tus documentos de manera efectiva<\/p>","protected":false},"template":"","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"class_list":["post-38049","juzgado-de-paz","type-juzgado-de-paz","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ezkio-Itsaso - Registro Central de Espa\u00f1a<\/title>\n<meta name=\"description\" content=\"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/ezkio-itsaso\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ezkio-Itsaso - Registro Central de Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/ezkio-itsaso\/\" \/>\n<meta property=\"og:site_name\" content=\"Registro Central de Espa\u00f1a\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/\",\"url\":\"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/\",\"name\":\"Ezkio-Itsaso - Registro Central de Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\/\/registrocentral.es\/#website\"},\"datePublished\":\"2024-09-24T18:38:42+00:00\",\"description\":\"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.registrocentral.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"juzgado de paz\",\"item\":\"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ezkio-Itsaso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/registrocentral.es\/#website\",\"url\":\"https:\/\/registrocentral.es\/\",\"name\":\"Registro Central de Espa\u00f1a\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/registrocentral.es\/#organization\"},\"alternateName\":\"Registro Central de Espa\u00f1a\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/registrocentral.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/registrocentral.es\/#organization\",\"name\":\"Registro Central de Espa\u00f1a\",\"alternateName\":\"Registro Central\",\"url\":\"https:\/\/registrocentral.es\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/registrocentral.es\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.registrocentral.es\/wp-content\/uploads\/2026\/03\/registrocentral.webp\",\"contentUrl\":\"https:\/\/www.registrocentral.es\/wp-content\/uploads\/2026\/03\/registrocentral.webp\",\"width\":320,\"height\":431,\"caption\":\"Registro Central de Espa\u00f1a\"},\"image\":{\"@id\":\"https:\/\/registrocentral.es\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ezkio-Itsaso - Registro Central de Espa\u00f1a","description":"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/ezkio-itsaso\/","og_locale":"fr_FR","og_type":"article","og_title":"Ezkio-Itsaso - Registro Central de Espa\u00f1a","og_description":"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.","og_url":"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/ezkio-itsaso\/","og_site_name":"Registro Central de Espa\u00f1a","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/","url":"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/","name":"Ezkio-Itsaso - Registro Central de Espa\u00f1a","isPartOf":{"@id":"https:\/\/registrocentral.es\/#website"},"datePublished":"2024-09-24T18:38:42+00:00","description":"Los Juzgados de Paz en Ezkio-Itsaso desempe\u00f1an un papel fundamental en municipios donde no existen juzgados de primera instancia e instrucci\u00f3n. Se encargan de gestionar asuntos civiles y penales de menor relevancia, adem\u00e1s de algunas funciones administrativas, como la tramitaci\u00f3n de ciertos actos relacionados con el Registro Civil. En este art\u00edculo, te proporcionamos informaci\u00f3n detallada sobre los Juzgados de Paz en Ezkio-Itsaso y sus funciones.","breadcrumb":{"@id":"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.registrocentral.es\/juzgado-de-paz\/ezkio-itsaso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.registrocentral.es\/"},{"@type":"ListItem","position":2,"name":"juzgado de paz","item":"https:\/\/www.registrocentral.es\/fr\/juzgado-de-paz\/"},{"@type":"ListItem","position":3,"name":"Ezkio-Itsaso"}]},{"@type":"WebSite","@id":"https:\/\/registrocentral.es\/#website","url":"https:\/\/registrocentral.es\/","name":"Registre Central d'Espagne","description":"","publisher":{"@id":"https:\/\/registrocentral.es\/#organization"},"alternateName":"Registro Central de Espa\u00f1a","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/registrocentral.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/registrocentral.es\/#organization","name":"Registre Central d'Espagne","alternateName":"Registro Central","url":"https:\/\/registrocentral.es\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/registrocentral.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.registrocentral.es\/wp-content\/uploads\/2026\/03\/registrocentral.webp","contentUrl":"https:\/\/www.registrocentral.es\/wp-content\/uploads\/2026\/03\/registrocentral.webp","width":320,"height":431,"caption":"Registro Central de Espa\u00f1a"},"image":{"@id":"https:\/\/registrocentral.es\/#\/schema\/logo\/image\/"}}]}},"spectra_custom_meta":{"stick-header-meta":[""],"adv-header-id-meta":[""],"theme-transparent-header-meta":[""],"footer-sml-layout":[""],"ast-site-content-layout":["full-width-container"],"_uag_custom_page_level_css":[""],"_edit_last":["2"],"_edit_lock":["1724711907:2"],"_uag_css_file_name":["uag-css-38049.css"],"_uag_page_assets":["a:9:{s:3:\"css\";s:0:\"\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:7:{i:0;s:11:\"core\/search\";i:1;s:10:\"core\/group\";i:2;s:12:\"core\/heading\";i:3;s:17:\"core\/latest-posts\";i:4;s:20:\"core\/latest-comments\";i:5;s:13:\"core\/archives\";i:6;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:0;s:11:\"uag_version\";s:10:\"1778201736\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"],"comunidad":["Pa\u00eds Vasco"],"provincia":["Gipuzkoa"],"locacion":["Tolosa"],"municipio":["Ezkio-Itsaso"],"direccion":["Calle Santa Lutzi"],"telefono":["943721303"],"fax":["943725666"]},"uagb_featured_image_src":[],"uagb_author_info":{"display_name":"Osorio","author_link":"https:\/\/www.registrocentral.es\/fr\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"El Juzgado de Paz de Ezkio-Itsaso ofrece una serie de servicios judiciales y civiles esenciales para los residentes de la localidad. Si necesitas realizar tr\u00e1mites relacionados con el estado civil, actas, o demandas menores, aqu\u00ed te explicamos todo lo que necesitas saber para gestionar tus documentos de manera efectiva","_links":{"self":[{"href":"https:\/\/www.registrocentral.es\/fr\/wp-json\/wp\/v2\/juzgado-de-paz\/38049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.registrocentral.es\/fr\/wp-json\/wp\/v2\/juzgado-de-paz"}],"about":[{"href":"https:\/\/www.registrocentral.es\/fr\/wp-json\/wp\/v2\/types\/juzgado-de-paz"}],"wp:attachment":[{"href":"https:\/\/www.registrocentral.es\/fr\/wp-json\/wp\/v2\/media?parent=38049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}